{"id":9997,"count":0,"description":"","link":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates","name":"Metabolic Rate","slug":"devices-for-calculating-metabolic-rates","taxonomy":"product_cat","parent":9911,"meta":{"b2bking_group_b2c":[],"b2bking_group_0":[],"b2bking_group_892":[],"b2bking_group_888":[]},"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Devices for calculating metabolic rates | Medncare.gr<\/title>\n<meta name=\"description\" content=\"Discover a huge variety of Devices for calculating metabolic rates &amp; get online with instant shipping &amp; free shipping over 49 \u20ac!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devices for calculating metabolic rates | Medncare.gr\" \/>\n<meta property=\"og:description\" content=\"Discover a huge variety of Devices for calculating metabolic rates &amp; get online with instant shipping &amp; free shipping over 49 \u20ac!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates\" \/>\n<meta property=\"og:site_name\" content=\"Online Med&amp;Care\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medncare.gr\/wp-content\/uploads\/2024\/06\/og-image-online-farmakeio-medncare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/medncare.gr\\\/en\\\/c\\\/diagnostics\\\/diagnostic-equipment\\\/devices-for-calculating-metabolic-rates\",\"url\":\"https:\\\/\\\/medncare.gr\\\/en\\\/c\\\/diagnostics\\\/diagnostic-equipment\\\/devices-for-calculating-metabolic-rates\",\"name\":\"Devices for calculating metabolic rates | Medncare.gr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medncare.gr\\\/en#website\"},\"description\":\"Discover a huge variety of Devices for calculating metabolic rates & get online with instant shipping & free shipping over 49 \u20ac!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medncare.gr\\\/en\\\/c\\\/diagnostics\\\/diagnostic-equipment\\\/devices-for-calculating-metabolic-rates#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medncare.gr\\\/en\\\/c\\\/diagnostics\\\/diagnostic-equipment\\\/devices-for-calculating-metabolic-rates#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/medncare.gr\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diagnostics\",\"item\":\"https:\\\/\\\/medncare.gr\\\/en\\\/c\\\/diagnostics\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diagnostic Equipment\",\"item\":\"https:\\\/\\\/medncare.gr\\\/en\\\/c\\\/diagnostics\\\/diagnostic-equipment\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Metabolic Rate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medncare.gr\\\/en#website\",\"url\":\"https:\\\/\\\/medncare.gr\\\/en\",\"name\":\"Online Med&amp;Care\",\"description\":\"\u039f\u03bc\u03bf\u03c1\u03c6\u03b9\u03ac, \u03a5\u03b3\u03b5\u03af\u03b1, \u0394\u03b9\u03b1\u03c4\u03c1\u03bf\u03c6\u03ae\",\"publisher\":{\"@id\":\"https:\\\/\\\/medncare.gr\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medncare.gr\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medncare.gr\\\/en#organization\",\"name\":\"Medncare\",\"url\":\"https:\\\/\\\/medncare.gr\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medncare.gr\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medncare.gr\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/OGimage.jpg\",\"contentUrl\":\"https:\\\/\\\/medncare.gr\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/OGimage.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Medncare\"},\"image\":{\"@id\":\"https:\\\/\\\/medncare.gr\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Devices for calculating metabolic rates | Medncare.gr","description":"Discover a huge variety of Devices for calculating metabolic rates & get online with instant shipping & free shipping over 49 \u20ac!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates","og_locale":"en_US","og_type":"article","og_title":"Devices for calculating metabolic rates | Medncare.gr","og_description":"Discover a huge variety of Devices for calculating metabolic rates & get online with instant shipping & free shipping over 49 \u20ac!","og_url":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates","og_site_name":"Online Med&amp;Care","og_image":[{"width":1200,"height":630,"url":"https:\/\/medncare.gr\/wp-content\/uploads\/2024\/06\/og-image-online-farmakeio-medncare.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates","url":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates","name":"Devices for calculating metabolic rates | Medncare.gr","isPartOf":{"@id":"https:\/\/medncare.gr\/en#website"},"description":"Discover a huge variety of Devices for calculating metabolic rates & get online with instant shipping & free shipping over 49 \u20ac!","breadcrumb":{"@id":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment\/devices-for-calculating-metabolic-rates#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/medncare.gr\/en"},{"@type":"ListItem","position":2,"name":"Diagnostics","item":"https:\/\/medncare.gr\/en\/c\/diagnostics"},{"@type":"ListItem","position":3,"name":"Diagnostic Equipment","item":"https:\/\/medncare.gr\/en\/c\/diagnostics\/diagnostic-equipment"},{"@type":"ListItem","position":4,"name":"Metabolic Rate"}]},{"@type":"WebSite","@id":"https:\/\/medncare.gr\/en#website","url":"https:\/\/medncare.gr\/en","name":"Online Med&amp;Care","description":"\u039f\u03bc\u03bf\u03c1\u03c6\u03b9\u03ac, \u03a5\u03b3\u03b5\u03af\u03b1, \u0394\u03b9\u03b1\u03c4\u03c1\u03bf\u03c6\u03ae","publisher":{"@id":"https:\/\/medncare.gr\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medncare.gr\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/medncare.gr\/en#organization","name":"Medncare","url":"https:\/\/medncare.gr\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medncare.gr\/en#\/schema\/logo\/image\/","url":"https:\/\/medncare.gr\/wp-content\/uploads\/2022\/07\/OGimage.jpg","contentUrl":"https:\/\/medncare.gr\/wp-content\/uploads\/2022\/07\/OGimage.jpg","width":1200,"height":630,"caption":"Medncare"},"image":{"@id":"https:\/\/medncare.gr\/en#\/schema\/logo\/image\/"}}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/medncare.gr\/en\/wp-json\/wp\/v2\/product_cat\/9997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medncare.gr\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/medncare.gr\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/medncare.gr\/en\/wp-json\/wp\/v2\/product_cat\/9911"}],"wp:post_type":[{"href":"https:\/\/medncare.gr\/en\/wp-json\/wp\/v2\/product?product_cat=9997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}